{"id":3381,"date":"2020-03-16T17:50:43","date_gmt":"2020-03-16T16:50:43","guid":{"rendered":"https:\/\/commonspolis.org\/?p=3381"},"modified":"2020-03-16T19:24:12","modified_gmt":"2020-03-16T18:24:12","slug":"trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte","status":"publish","type":"post","link":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/","title":{"rendered":"Trois petites gouttes de salive dans l&rsquo;air ou Comment l&rsquo;on pouvait tomber devant un baiser, devant un \u00e9treinte."},"content":{"rendered":"<p>\u00ab\u00a0Et un jour, le monde fut rempli de la terrible promesse d&rsquo;une apocalypse virale et soudain, les fronti\u00e8res qui \u00e9taient d\u00e9fendues par les guerres furent bris\u00e9es par des gouttelettes de crachat, il y eut \u00e9quit\u00e9 dans la contagion, r\u00e9partie pareillement entre riches et pauvres, les puissances qui se sentaient infaillibles virent comment on pouvait tomber devant un baiser, devant une \u00e9treinte.<\/p>\n<p>&nbsp;<\/p>\n<p>Et nous avons r\u00e9alis\u00e9 ce qui \u00e9tait important et ce qui ne l&rsquo;\u00e9tait pas, et puis une infirmi\u00e8re est devenue plus indispensable qu&rsquo;un footballeur, et un h\u00f4pital est devenu plus urgent qu&rsquo;un missile. Les lumi\u00e8res s&rsquo;\u00e9teignaient dans les stades, les concerts se sont arr\u00eat\u00e9s, les tournages de films et les messes prirent fin, les r\u00e9unions de masse aussi, et puis, soudainement dans le monde, il y eut du temps pour r\u00e9fl\u00e9chir seul, et pour attendre \u00e0 la maison que tout le monde arrive et se rassemble devant des feux, des tables, des chaises \u00e0 bascule, des hamacs, pour raconter des histoires qui \u00e9taient sur le point d&rsquo;\u00eatre oubli\u00e9es.<br \/>\n&nbsp;<\/p>\n<p>Trois petites gouttes de salive dans l&rsquo;air, nous ont pouss\u00e9 \u00e0 prendre soin des personnes \u00e2g\u00e9es, \u00e0 privil\u00e9gier la science \u00e0 l&rsquo;\u00e9conomie, nous ont fait comprendre que ce ne sont pas seulement les indigents qui apportent des fl\u00e9aux, que notre pyramide des valeurs \u00e9tait invers\u00e9e, que la vie passait toujours en premier et que d&rsquo;autres choses \u00e9taient accessoires.<br \/>\n&nbsp;<\/p>\n<p>Il n&rsquo;y a pas d&rsquo;endroit s\u00fbr, dans notre esprit il y a de la place pour tous et nous commen\u00e7ons \u00e0 souhaiter du bien \u00e0 notre voisin, nous avons besoin qu&rsquo;il soit en s\u00e9curit\u00e9, nous avons besoin qu&rsquo;il ne tombe pas malade, qu&rsquo;il vive longtemps, qu&rsquo;il soit heureux et malgr\u00e9 une parano\u00efa bouillie dans le d\u00e9sinfectant, nous r\u00e9alisons que si j&rsquo;ai de l&rsquo;eau et qu&rsquo;un autre n&rsquo;en a pas, ma vie est en danger.<br \/>\n&nbsp;<\/p>\n<p>Nous sommes redevenus un village, la solidarit\u00e9 se teint de peur et au risque de nous enfermer dans l&rsquo;isolement, il n&rsquo;y a qu&rsquo;une seule alternative : \u00eatre mieux ensemble.<br \/>\n&nbsp;<\/p>\n<p>Si tout va bien, tout changera \u00e0 jamais. Les regards seront notre salut et nous r\u00e9serverons le baiser seulement \u00e0 ceux qui ont d\u00e9j\u00e0 gagn\u00e9 notre c\u0153ur, quand toutes les cartes seront teint\u00e9es de rouge avec la pr\u00e9sence de celui qui couronne, les fronti\u00e8res ne seront pas n\u00e9cessaires et le passage de ceux qui viennent donner de l&rsquo;espoir sera bien accueilli quelle que soit sa langue et sa couleur de peau, peu importe que je ne comprenne pas ton mode de vie, si ta foi n&rsquo;est pas la mienne, il suffira de t&rsquo;encourager \u00e0 tendre la main quand personne d&rsquo;autre ne veut le faire.<br \/>\n&nbsp;<\/p>\n<p>Il se peut, ce n&rsquo;est qu&rsquo;une possibilit\u00e9, que ce virus nous rende plus humains et que d&rsquo;une atroce inondation naisse un nouveau pacte, accompagn\u00e9 d&rsquo;un rameau d&rsquo;olivier d&rsquo;o\u00f9 il partira de z\u00e9ro.\u00a0\u00bb<br \/>\n&nbsp;<\/p>\n<p>Texte trouv\u00e9 et partag\u00e9 sur les r\u00e9seaux sociaux, dont l&rsquo;auteur est \u00e0 ce jour anonyme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0Et un jour, le monde fut rempli de la terrible promesse d&rsquo;une apocalypse virale et soudain, les fronti\u00e8res qui \u00e9taient d\u00e9fendues par les guerres furent bris\u00e9es par des gouttelettes de crachat, il y eut \u00e9quit\u00e9 dans la contagion, r\u00e9partie pareillement entre riches et pauvres, les puissances qui se sentaient infaillibles virent comment on pouvait tomber&hellip;<\/p>\n","protected":false},"author":2,"featured_media":3377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[137,157],"class_list":["post-3381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiration","tag-bientraitance","tag-ecofeminisme","category-24","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trois petites gouttes de salive dans l&#039;air ou Comment l&#039;on pouvait tomber devant un baiser, devant un \u00e9treinte. &#8902; Commonspolis<\/title>\n<meta name=\"description\" content=\"16 mars, 2020 | &quot;Et un jour, le monde fut rempli de la terrible promesse d&#039;une apocalypse virale et soudain, les fronti\u00e8res qui \u00e9taient d\u00e9fendues par les guerres furent\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trois petites gouttes de salive dans l&#039;air ou Comment l&#039;on pouvait tomber devant un baiser, devant un \u00e9treinte. &#8902; Commonspolis\" \/>\n<meta property=\"og:description\" content=\"16 mars, 2020 | &quot;Et un jour, le monde fut rempli de la terrible promesse d&#039;une apocalypse virale et soudain, les fronti\u00e8res qui \u00e9taient d\u00e9fendues par les guerres furent\" \/>\n<meta property=\"og:url\" content=\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/\" \/>\n<meta property=\"og:site_name\" content=\"Commonspolis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/commonspolis\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-16T16:50:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-16T18:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@commonspolis\" \/>\n<meta name=\"twitter:site\" content=\"@commonspolis\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/\"},\"author\":{\"name\":\"redaccion\",\"@id\":\"https:\/\/commonspolis.org\/fr\/#\/schema\/person\/5619687a9571709fdc6ef04a9b6f6635\"},\"headline\":\"Trois petites gouttes de salive dans l&rsquo;air ou Comment l&rsquo;on pouvait tomber devant un baiser, devant un \u00e9treinte.\",\"datePublished\":\"2020-03-16T16:50:43+00:00\",\"dateModified\":\"2020-03-16T18:24:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/\"},\"wordCount\":562,\"publisher\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg\",\"keywords\":[\"bientraitance\",\"\u00e9cofeminisme\"],\"articleSection\":[\"Inspiration\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/\",\"url\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/\",\"name\":\"Trois petites gouttes de salive dans l'air ou Comment l'on pouvait tomber devant un baiser, devant un \u00e9treinte. &#8902; Commonspolis\",\"isPartOf\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg\",\"datePublished\":\"2020-03-16T16:50:43+00:00\",\"dateModified\":\"2020-03-16T18:24:12+00:00\",\"description\":\"16 mars, 2020 | \\\"Et un jour, le monde fut rempli de la terrible promesse d'une apocalypse virale et soudain, les fronti\u00e8res qui \u00e9taient d\u00e9fendues par les guerres furent\",\"breadcrumb\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#primaryimage\",\"url\":\"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg\",\"contentUrl\":\"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/commonspolis.org\/fr\/pagina-ejemplo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trois petites gouttes de salive dans l&#8217;air ou Comment l&#8217;on pouvait tomber devant un baiser, devant un \u00e9treinte.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/commonspolis.org\/fr\/#website\",\"url\":\"https:\/\/commonspolis.org\/fr\/\",\"name\":\"Commonspolis\",\"description\":\"Tisser des r\u00e9seaux et des cultures citoyennes pour le changement \",\"publisher\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/commonspolis.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/commonspolis.org\/fr\/#organization\",\"name\":\"CommonsPolis\",\"url\":\"https:\/\/commonspolis.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/commonspolis.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/commonspolis.org\/wp-content\/uploads\/2019\/01\/Logo_commonspolis_1200x628.png\",\"contentUrl\":\"https:\/\/commonspolis.org\/wp-content\/uploads\/2019\/01\/Logo_commonspolis_1200x628.png\",\"width\":1200,\"height\":628,\"caption\":\"CommonsPolis\"},\"image\":{\"@id\":\"https:\/\/commonspolis.org\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/commonspolis\/\",\"https:\/\/x.com\/commonspolis\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/commonspolis.org\/fr\/#\/schema\/person\/5619687a9571709fdc6ef04a9b6f6635\",\"name\":\"redaccion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trois petites gouttes de salive dans l'air ou Comment l'on pouvait tomber devant un baiser, devant un \u00e9treinte. &#8902; Commonspolis","description":"16 mars, 2020 | \"Et un jour, le monde fut rempli de la terrible promesse d'une apocalypse virale et soudain, les fronti\u00e8res qui \u00e9taient d\u00e9fendues par les guerres furent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/","og_locale":"fr_FR","og_type":"article","og_title":"Trois petites gouttes de salive dans l'air ou Comment l'on pouvait tomber devant un baiser, devant un \u00e9treinte. &#8902; Commonspolis","og_description":"16 mars, 2020 | \"Et un jour, le monde fut rempli de la terrible promesse d'une apocalypse virale et soudain, les fronti\u00e8res qui \u00e9taient d\u00e9fendues par les guerres furent","og_url":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/","og_site_name":"Commonspolis","article_publisher":"https:\/\/www.facebook.com\/commonspolis\/","article_published_time":"2020-03-16T16:50:43+00:00","article_modified_time":"2020-03-16T18:24:12+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg","type":"image\/jpeg"}],"author":"redaccion","twitter_card":"summary_large_image","twitter_creator":"@commonspolis","twitter_site":"@commonspolis","twitter_misc":{"\u00c9crit par":"redaccion","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#article","isPartOf":{"@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/"},"author":{"name":"redaccion","@id":"https:\/\/commonspolis.org\/fr\/#\/schema\/person\/5619687a9571709fdc6ef04a9b6f6635"},"headline":"Trois petites gouttes de salive dans l&rsquo;air ou Comment l&rsquo;on pouvait tomber devant un baiser, devant un \u00e9treinte.","datePublished":"2020-03-16T16:50:43+00:00","dateModified":"2020-03-16T18:24:12+00:00","mainEntityOfPage":{"@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/"},"wordCount":562,"publisher":{"@id":"https:\/\/commonspolis.org\/fr\/#organization"},"image":{"@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#primaryimage"},"thumbnailUrl":"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg","keywords":["bientraitance","\u00e9cofeminisme"],"articleSection":["Inspiration"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/","url":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/","name":"Trois petites gouttes de salive dans l'air ou Comment l'on pouvait tomber devant un baiser, devant un \u00e9treinte. &#8902; Commonspolis","isPartOf":{"@id":"https:\/\/commonspolis.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#primaryimage"},"image":{"@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#primaryimage"},"thumbnailUrl":"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg","datePublished":"2020-03-16T16:50:43+00:00","dateModified":"2020-03-16T18:24:12+00:00","description":"16 mars, 2020 | \"Et un jour, le monde fut rempli de la terrible promesse d'une apocalypse virale et soudain, les fronti\u00e8res qui \u00e9taient d\u00e9fendues par les guerres furent","breadcrumb":{"@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#primaryimage","url":"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg","contentUrl":"https:\/\/commonspolis.org\/wp-content\/uploads\/2020\/03\/foto_inspiration_3-gotitas-de-saliva-en-el-aire.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/commonspolis.org\/fr\/inspiration\/trois-petites-gouttes-de-salive-dans-lair-ou-comment-lon-pouvait-tomber-devant-un-baiser-devant-un-etreinte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/commonspolis.org\/fr\/pagina-ejemplo\/"},{"@type":"ListItem","position":2,"name":"Trois petites gouttes de salive dans l&#8217;air ou Comment l&#8217;on pouvait tomber devant un baiser, devant un \u00e9treinte."}]},{"@type":"WebSite","@id":"https:\/\/commonspolis.org\/fr\/#website","url":"https:\/\/commonspolis.org\/fr\/","name":"Commonspolis","description":"Tisser des r\u00e9seaux et des cultures citoyennes pour le changement ","publisher":{"@id":"https:\/\/commonspolis.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/commonspolis.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/commonspolis.org\/fr\/#organization","name":"CommonsPolis","url":"https:\/\/commonspolis.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/commonspolis.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/commonspolis.org\/wp-content\/uploads\/2019\/01\/Logo_commonspolis_1200x628.png","contentUrl":"https:\/\/commonspolis.org\/wp-content\/uploads\/2019\/01\/Logo_commonspolis_1200x628.png","width":1200,"height":628,"caption":"CommonsPolis"},"image":{"@id":"https:\/\/commonspolis.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/commonspolis\/","https:\/\/x.com\/commonspolis"]},{"@type":"Person","@id":"https:\/\/commonspolis.org\/fr\/#\/schema\/person\/5619687a9571709fdc6ef04a9b6f6635","name":"redaccion"}]}},"_links":{"self":[{"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/posts\/3381"}],"collection":[{"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/comments?post=3381"}],"version-history":[{"count":0,"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/posts\/3381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/media\/3377"}],"wp:attachment":[{"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/media?parent=3381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/categories?post=3381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/commonspolis.org\/fr\/wp-json\/wp\/v2\/tags?post=3381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}